{"id":487,"date":"2026-05-11T09:35:20","date_gmt":"2026-05-11T07:35:20","guid":{"rendered":"https:\/\/profiforditas.hu\/?page_id=487"},"modified":"2026-05-11T14:34:48","modified_gmt":"2026-05-11T12:34:48","slug":"vorstellung","status":"publish","type":"page","link":"https:\/\/profiforditas.hu\/de\/bemutatkozas\/","title":{"rendered":"Vorstellung"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"487\" class=\"elementor elementor-487\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ff1e59 e-flex e-con-boxed e-con e-parent\" data-id=\"2ff1e59\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7241ae7 e-con-full e-flex e-con e-child\" data-id=\"7241ae7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a02b31d elementor-widget elementor-widget-image\" data-id=\"a02b31d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"254\" src=\"https:\/\/profiforditas.hu\/wp-content\/uploads\/2026\/05\/hero-german.webp\" class=\"attachment-large size-large wp-image-441\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-74251d7 e-con-full e-flex e-con e-child\" data-id=\"74251d7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e560ba1 elementor-widget elementor-widget-heading\" data-id=\"e560ba1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Vorstellung<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc42b69 elementor-widget elementor-widget-text-editor\" data-id=\"dc42b69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"logo_sdoc header-translates-hu\"><div class=\"logo_text\">Wann sollen Sie uns NICHT w\u00e4hlen? Wenn Sie eine grobe, ungef\u00e4hre \u00dcbersetzung m\u00f6chten, sind wir in diesem Fall NICHT die richtige Wahl! Senden Sie solche Anfragen nicht an unser \u00dcbersetzungsb\u00fcro!<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f44cc1f e-flex e-con-boxed e-con e-parent\" data-id=\"f44cc1f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-736a7e0 elementor-widget elementor-widget-heading\" data-id=\"736a7e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">forditas.hu, das hei\u00dft \u00dcbersetzungsb\u00fcro GB Europont\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cba5f8 elementor-widget elementor-widget-text-editor\" data-id=\"2cba5f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Das \u00dcbersetzungsb\u00fcro GB Europont Ford\u00edt\u00f3iroda Kft. wurde 2006 gegr\u00fcndet. Ich und mein Mitbesitzer waren motiviert, ein zuverl\u00e4ssiges, \u00fcber eine ausdehnte \u00dcbersetzerbasis verf\u00fcgendes, professionelles, aber zahlbares \u00dcbersetzungsb\u00fcro zustande zu bringen. Unter unseren Bestellern gibt es verschiene Firmen, Nonprofit Organisationen und Privatpersonen auch. Wir streben bei der Erf\u00fcllung unserer Auftr\u00e4ge \u2013au\u00dfer der Pr\u00e4zisit\u00e4t- nach der Schnelligkeit und der genauen Einhaltung der \u00fcbernommenen Fristen unter allen Bedingungen.<\/p><p>\u00a0<\/p><p class=\"translation-block\">Beim Start war f\u00fcr mich die mehr als 10j\u00e4hrige Erfahrung als \u00dcbersetzerin und Dolmetscherin eine gute Grundlage und die w\u00e4hrend dieser Jahre beherrschten Kenntnisse waren wichtige Bausteine bei der Ausgestaltung des Gesch\u00e4ftsmodells unserer Firma. Einfach, zuverl\u00e4ssig, zum zahlbaren Preis! Was wollen diese gut lautenden Worte bedeuten?<\/p><p>\u00a0<\/p><p><img decoding=\"async\" src=\"https:\/\/www.profiforditas.hu\/_data\/VFS_311b4f8fb919aa09093d1244b9141497.png\" alt=\"tiszta \u00e9s \u00e1tl\u00e1that\u00f3\" width=\"16\" height=\"16\" \/><strong>\u00a0Klar und transparent<\/strong>\u00a0In unserem B\u00fcro streben wir von Anfang an danach, um dem Besteller auf der m\u00f6glichst einfachsten Art nach einem Telefonat oder einer e-Mail, so schnell wie m\u00f6glich die Information dar\u00fcber zu geben, mit welcher Frist und zum welchen Preis der zu \u00fcbersetzende Text von uns \u00fcbernommen wird, damit unser Kunde keine andere Aufgabe hat wie die Benutzung der fertigen \u00dcbersetzung in dem erw\u00fcnschten Format ohne \u00dcberraschungen!<\/p><p>\u00a0<\/p><p><img decoding=\"async\" src=\"https:\/\/www.profiforditas.hu\/_data\/VFS_311b4f8fb919aa09093d1244b9141497.png\" alt=\"gyors \u00e9s megb\u00edzhat\u00f3\" width=\"16\" height=\"16\" \/>\u00a0<strong>Schnell und zuverl\u00e4ssig<\/strong>, weil wir uns unter allen Umst\u00e4nden an die \u00fcbernommenen Verpflichtungen halten. Die bestimmte \u00dcbersetzung wird immer von dem, den Fachbereich am besten kennenden \u00dcbersetzerkollegen angefertigt.<\/p><p>\u00a0<\/p><p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.profiforditas.hu\/_data\/VFS_311b4f8fb919aa09093d1244b9141497.png\" alt=\"kedvez\u0151 \u00e1r\" width=\"16\" height=\"16\" \/>\u00a0<strong>G\u00fcnstiger Preis<\/strong>! Unsere Besteller erfahren mehrmals, dass wir zu niedrigeren Preisen arbeiten als die Privat\u00fcbersetzer. Dessen Grund sind die regelm\u00e4\u00dfigen Auftr\u00e4ge und die Berechenbarkeit unserer Kollegen. Dabei ist wichtig wieder zu erw\u00e4hnen, dass ein gut organisiertes B\u00fcro den Kunden auch dadurch entlastet, dass es immer mit dem, den Fachbereich am besten kennenden Kollegen arbeitet.<\/p><p>\u00a0<\/p><p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.profiforditas.hu\/_data\/VFS_311b4f8fb919aa09093d1244b9141497.png\" alt=\"kisz\u00e1m\u00edthat\u00f3\" width=\"16\" height=\"16\" \/>\u00a0<strong>Berechenbar<\/strong>, weil z.B. bei einem Privat\u00fcbersetzer nicht voraussichtliche F\u00e4lle auftreten k\u00f6nnen und die \u00fcbernommene Frist kann scheitern und nicht zuletzt Sie k\u00f6nnen bei uns Ihre \u00dcbersetzungsanspr\u00fcche in jeder Fremdsprache bzw. die muttersprachige Lektorierung je nach Bedarf durch einen einzigen Kontakthalter erledigen.<\/p><p>\u00a0<\/p><p>Heute k\u00f6nnen wir sagen, dass wir in den letzten Jahren eine relevante Rolle auf dem \u00dcbersetzungsmarkt erwerben konnten, wir verf\u00fcgen \u00fcber eine Datenbasis mit etwa 300 \u00dcbersetzern, von denen wir mit ca. 50 \u00dcbersetzern regelm\u00e4\u00dfig zusammenarbeiten.<\/p><p>\u00a0<\/p><p>Seit unserer Gr\u00fcndung haben wir mehr als 25.000 Seiten in 34 Fremdsprachen \u00fcbersetzt, was die \u00dcbersetzung von mehr als 10 Millionen Charakter pro Jahr f\u00fcr etwa 200 Partner bedeutet.<\/p><p>\u00a0<\/p><p>Wir hoffen, dass wir bald auch Sie unter unseren Partnern begr\u00fc\u00dfen k\u00f6nnen!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ad6f49 elementor-widget elementor-widget-text-editor\" data-id=\"2ad6f49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Mit freundlichen Gr\u00fc\u00dfen:<br>Kristina Matyi<br>Gesch\u00e4ftsf\u00fchrerin<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a91c373 e-con-full e-flex e-con e-child\" data-id=\"a91c373\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95abf59 elementor-widget elementor-widget-heading\" data-id=\"95abf59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Referenzen:\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f8941d elementor-widget elementor-widget-text-editor\" data-id=\"4f8941d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li>3T-R-M System Bt.<\/li><li>ABBC Plant Kft.<\/li><li>Acer H\u0171t\u00e9stechnika Kft.<\/li><li>ACR Building Kft.<\/li><li>Agroimpex Hung\u00e1ria Kft.<\/li><li>Aircabin Rep\u00fcl\u0151g\u00e9pgy\u00e1r Ny\u00edrb\u00e1tor<\/li><li>ArtMax Kreat\u00edv \u00dcgyn\u00f6ks\u00e9g Kft.<\/li><li>Art-Vital Tervez\u0151iroda<\/li><li>Bel\u00fcgyminiszt\u00e9rium<\/li><li>Bev\u00e1ndorl\u00e1si Hivatal<\/li><li>BE-WE-GE Medical UG<\/li><li>Bicskei V\u00e1rosi B\u00edr\u00f3s\u00e1g<\/li><li>Bio-Szil Term\u00e9szetv\u00e9delmi \u00e9s K\u00f6rnyezetgazd\u00e1lkod\u00e1si<\/li><li>Nonprofit Kft.<\/li><li>Bodg\u00e1ny Petrol Kft.<\/li><li>Bogd\u00e1ny-Plusz Kft.<\/li><li>Budak\u00f6rny\u00e9ki \u00dcgy\u00e9szs\u00e9g<\/li><li>Budapest Airport<\/li><li>Carl Zeiss Sport Optikai Hung\u00e1ria Kft<\/li><li>CCE Hungary Kft.<\/li><li>Cembrit Kft.<\/li><li>Csenger, Nestta Cip\u0151ipari Kft.<\/li><li>DMS Dialogmarketing Kft.<\/li><li>\u00c9p\u00edt\u0151ipari \u00e9s Kereskedelmi Kft<\/li><li>Fackelmann Hung\u00e1ria Kft.<\/li><li>Fenster Plast Kft.<\/li><li>Fenstherm Ny\u00edl\u00e1ssz\u00e1r\u00f3gy\u00e1rt\u00f3 \u00e9s Kereskedelmi Kft.<\/li><li>Ferrotransz \u201998 Kft.<\/li><li>F\u0151taxi Budapest<\/li><li>Hitelap Zrt.<\/li><li>H-Net Nyelvi K\u00f6zpont Budapest<\/li><li>Hospitaly Kft.<\/li><li>Hunland Trade Kft.<\/li><li>IKR Zrt.<\/li><li>IT Help.hu Consulting Kft.<\/li><li>IT Jobs Szem\u00e9lyzeti Tan\u00e1csad\u00f3 Kft.<\/li><li>Josef Seibel Cip\u0151ipari Kft.<\/li><li>Kedd Kft.<\/li><li>Keleti H\u00e1romhat\u00e1r-Szeglet Kutat\u00f3-Fejleszt\u0151 K\u00f6zpont<\/li><li>K\u00f6zhaszn\u00fa Egyes\u00fclet<\/li><li>Kit\u0171n\u0151s\u00e9g-Fejleszt\u0151k Kft.<\/li><li>Leonardo Education Nonprofit Kft.<\/li><li>Lila Trade Bt.<\/li><li>Litamo Bt.<\/li><li>M3 aut\u00f3p\u00e1lya<\/li><li>Main Steel Kft.<\/li><li>Makrai Kamion Kft.<\/li><li>Mantar Konzervgy\u00e1r<\/li><li>Margit h\u00edd \u00e9p\u00edt\u00e9si munk\u00e1latai<\/li><li>Medik\u00e9mia Zrt.<\/li><li>Medis Hungary Kft.<\/li><li>Mercedes Kecskem\u00e9t<\/li><li>MHM Computer Hungary Kft.<\/li><li>Mondi Bags Hung\u00e1ria Kft.<\/li><li>Nestta Cip\u0151ipari Kft.<\/li><li>Ny\u00edregyh\u00e1za Spartacus Football Club Kft.<\/li><li>Ny\u00edregyh\u00e1zi B\u00edr\u00f3s\u00e1g<\/li><li>Ny\u00edr-Mez\u0151g\u00e9p Ipari \u00e9s Kereskedelmi Kft.<\/li><li>Palermo Panzi\u00f3 Ny\u00edregyh\u00e1za<\/li><li>Paor-V\u00edz Ker. Kft.<\/li><li>PAS Kft.<\/li><li>Piercing-Hungary Kft.<\/li><li>Portos Hungary Kft.<\/li><li>P\u00fcsp\u00f6klad\u00e1nyi Gy\u00f3gyf\u00fcrd\u0151<\/li><li>Rosa Villa Kft.<\/li><li>SADE-Magyarorsz\u00e1g M\u00e9ly\u00e9p\u00edt\u0151 Kft.<\/li><li>Salg\u00f3-Rakt\u00e1rtechnika Kft.<\/li><li>Speedfitness Kft.<\/li><li>Still Kft.<\/li><li>Ottis.hu Kft.<\/li><li>Szinmark Kereskedelmi Kft.<\/li><li>Te-Art Zrt.<\/li><li>The Guidency Kft.<\/li><li>Tracon Budapest Kft.<\/li><li>Unico Logistics Kft.<\/li><li>Velence Spa Hotel<\/li><li>Vodafone Magyarorsz\u00e1g Kft.<\/li><li>ZENIT MOBILG\u00c1T Kft.<\/li><li>Z\u00f6ld \u00dajs\u00e1g Zrt.<\/li><li>Z\u00f6ldinvest Kft.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31a24f4 elementor-widget elementor-widget-heading\" data-id=\"31a24f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Einige Feedbacks von unseren Partnern:<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-252ad05 elementor-testimonial--align-left elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"252ad05\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;3&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;slides_per_view_laptop&quot;:&quot;3&quot;,&quot;slides_per_view_tablet_extra&quot;:&quot;3&quot;,&quot;slides_per_view_tablet&quot;:&quot;3&quot;,&quot;slides_per_view_mobile_extra&quot;:&quot;2&quot;,&quot;slides_per_view_mobile&quot;:&quot;1&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\u201eKorrekte Arbeit zum korrekten Preis.\u201d\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">P\u00e1l Edina, Office manager<\/span><span class=\"elementor-testimonial__title\">Mondi Bags Hung\u00e1ria Kft.<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\u201eSie halten immer ein, was sie versprechen und sie sind sehr flexible.\u201d\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Ga\u00e1ln\u00e9 Andi<\/span><span class=\"elementor-testimonial__title\">Josef Seibel Cip\u0151ipari Kft<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\u201eEs ist ein zuverl\u00e4ssiges, korrektes \u00dcbersetzungsb\u00fcro, ich empfehle es meinen Partnern gern weiter.\u201d\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">D\u00e1ny\u00e1di Andrea<\/span><span class=\"elementor-testimonial__title\">Bioszil Nonprofit Kft.<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\u201eVielen Dank f\u00fcr die schnelle und genaue Arbeit!\u201d\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Szalczgruber Mariann, Kultur- und Marketingmanager<\/span><span class=\"elementor-testimonial__title\">Velence Therm\u00e1l Spa<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\u201eEs ist ein schnelles, pr\u00e4zises, sehr flexibles und korrektes \u00dcbersetzungsb\u00fcro.\u201d\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Katona Szilvia, Marketing- und Vertriebsmanager Export<\/span><span class=\"elementor-testimonial__title\">Medik\u00e9mia Zrt.<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t\u201eWenn ich sie fr\u00fcher getroffen h\u00e4tte, h\u00e4tte ich unser Unternehmen von vielen Unannehmlichkeiten verschont\u2026\u201d\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Buz\u00e1k Viktor<\/span><span class=\"elementor-testimonial__title\">Z\u00f6ldinvest Kft.<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Bemutatkoz\u00e1s Mikor NE v\u00e1lasszon minket? Ha elnagyolt, k\u00f6r\u00fclbel\u00fcli ford\u00edt\u00e1st szeretne, arra NEM mi vagyunk a megfelel\u0151 v\u00e1laszt\u00e1s! Ilyen jelleg\u0171 aj\u00e1nlatk\u00e9r\u00e9seit [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":527,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-487","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bemutatkoz\u00e1s - Ford\u00edt\u00f3 iroda<\/title>\n<meta name=\"description\" content=\"Megrendel\u0151ink k\u00f6z\u00f6tt megtal\u00e1lhat\u00f3ak k\u00fcl\u00f6nb\u00f6z\u0151 c\u00e9gek, non profit szervezetek \u00e9s mag\u00e1nemberek egyar\u00e1nt. Megb\u00edz\u00e1saink teljes\u00edt\u00e9se sor\u00e1n - a precizit\u00e1son t\u00falmen\u0151en - t\u00f6reksz\u00fcnk a gyorsas\u00e1gra \u00e9s a v\u00e1llalt hat\u00e1rid\u0151k minden k\u00f6r\u00fclm\u00e9nyek k\u00f6z\u00f6tti pontos betart\u00e1s\u00e1ra\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/profiforditas.hu\/de\/vorstellung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bemutatkoz\u00e1s\" \/>\n<meta property=\"og:description\" content=\"Megrendel\u0151ink k\u00f6z\u00f6tt megtal\u00e1lhat\u00f3ak k\u00fcl\u00f6nb\u00f6z\u0151 c\u00e9gek, non profit szervezetek \u00e9s mag\u00e1nemberek egyar\u00e1nt. Megb\u00edz\u00e1saink teljes\u00edt\u00e9se sor\u00e1n - a precizit\u00e1son t\u00falmen\u0151en - t\u00f6reksz\u00fcnk a gyorsas\u00e1gra \u00e9s a v\u00e1llalt hat\u00e1rid\u0151k minden k\u00f6r\u00fclm\u00e9nyek k\u00f6z\u00f6tti pontos betart\u00e1s\u00e1ra\" \/>\n<meta property=\"og:url\" content=\"https:\/\/profiforditas.hu\/de\/vorstellung\/\" \/>\n<meta property=\"og:site_name\" content=\"Ford\u00edt\u00f3 iroda\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T12:34:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/profiforditas.hu\/wp-content\/uploads\/2026\/05\/logo-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"177\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/profiforditas.hu\\\/bemutatkozas\\\/\",\"url\":\"https:\\\/\\\/profiforditas.hu\\\/bemutatkozas\\\/\",\"name\":\"Bemutatkoz\u00e1s - Ford\u00edt\u00f3 iroda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/profiforditas.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/profiforditas.hu\\\/bemutatkozas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/profiforditas.hu\\\/bemutatkozas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/profiforditas.hu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo-1.webp\",\"datePublished\":\"2026-05-11T07:35:20+00:00\",\"dateModified\":\"2026-05-11T12:34:48+00:00\",\"description\":\"Megrendel\u0151ink k\u00f6z\u00f6tt megtal\u00e1lhat\u00f3ak k\u00fcl\u00f6nb\u00f6z\u0151 c\u00e9gek, non profit szervezetek \u00e9s mag\u00e1nemberek egyar\u00e1nt. Megb\u00edz\u00e1saink teljes\u00edt\u00e9se sor\u00e1n - a precizit\u00e1son t\u00falmen\u0151en - t\u00f6reksz\u00fcnk a gyorsas\u00e1gra \u00e9s a v\u00e1llalt hat\u00e1rid\u0151k minden k\u00f6r\u00fclm\u00e9nyek k\u00f6z\u00f6tti pontos betart\u00e1s\u00e1ra\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/profiforditas.hu\\\/bemutatkozas\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/profiforditas.hu\\\/bemutatkozas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/profiforditas.hu\\\/bemutatkozas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/profiforditas.hu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo-1.webp\",\"contentUrl\":\"https:\\\/\\\/profiforditas.hu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo-1.webp\",\"width\":800,\"height\":177},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/profiforditas.hu\\\/bemutatkozas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/profiforditas.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bemutatkoz\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/profiforditas.hu\\\/#website\",\"url\":\"https:\\\/\\\/profiforditas.hu\\\/\",\"name\":\"Ford\u00edt\u00f3 iroda\",\"description\":\"Profi ford\u00edt\u00e1sok gyorsan \u00e9s egyszer\u0171en!\",\"publisher\":{\"@id\":\"https:\\\/\\\/profiforditas.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/profiforditas.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/profiforditas.hu\\\/#organization\",\"name\":\"Ford\u00edt\u00f3 iroda\",\"url\":\"https:\\\/\\\/profiforditas.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/profiforditas.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/profiforditas.hu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo-1.webp\",\"contentUrl\":\"https:\\\/\\\/profiforditas.hu\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo-1.webp\",\"width\":800,\"height\":177,\"caption\":\"Ford\u00edt\u00f3 iroda\"},\"image\":{\"@id\":\"https:\\\/\\\/profiforditas.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vorstellung \u2013 \u00dcbersetzungsb\u00fcro","description":"Zu unseren Auftraggebern z\u00e4hlen verschiedene Unternehmen, gemeinn\u00fctzige Organisationen sowie Privatpersonen. Bei der Ausf\u00fchrung unserer Auftr\u00e4ge streben wir neben Pr\u00e4zision auch Schnelligkeit und die genaue Einhaltung der vereinbarten Fristen unter allen Umst\u00e4nden an.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/profiforditas.hu\/de\/vorstellung\/","og_locale":"de_DE","og_type":"article","og_title":"Bemutatkoz\u00e1s","og_description":"Megrendel\u0151ink k\u00f6z\u00f6tt megtal\u00e1lhat\u00f3ak k\u00fcl\u00f6nb\u00f6z\u0151 c\u00e9gek, non profit szervezetek \u00e9s mag\u00e1nemberek egyar\u00e1nt. Megb\u00edz\u00e1saink teljes\u00edt\u00e9se sor\u00e1n - a precizit\u00e1son t\u00falmen\u0151en - t\u00f6reksz\u00fcnk a gyorsas\u00e1gra \u00e9s a v\u00e1llalt hat\u00e1rid\u0151k minden k\u00f6r\u00fclm\u00e9nyek k\u00f6z\u00f6tti pontos betart\u00e1s\u00e1ra","og_url":"https:\/\/profiforditas.hu\/de\/vorstellung\/","og_site_name":"Ford\u00edt\u00f3 iroda","article_modified_time":"2026-05-11T12:34:48+00:00","og_image":[{"width":800,"height":177,"url":"https:\/\/profiforditas.hu\/wp-content\/uploads\/2026\/05\/logo-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/profiforditas.hu\/bemutatkozas\/","url":"https:\/\/profiforditas.hu\/bemutatkozas\/","name":"Vorstellung \u2013 \u00dcbersetzungsb\u00fcro","isPartOf":{"@id":"https:\/\/profiforditas.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/profiforditas.hu\/bemutatkozas\/#primaryimage"},"image":{"@id":"https:\/\/profiforditas.hu\/bemutatkozas\/#primaryimage"},"thumbnailUrl":"https:\/\/profiforditas.hu\/wp-content\/uploads\/2026\/05\/logo-1.webp","datePublished":"2026-05-11T07:35:20+00:00","dateModified":"2026-05-11T12:34:48+00:00","description":"Zu unseren Auftraggebern z\u00e4hlen verschiedene Unternehmen, gemeinn\u00fctzige Organisationen sowie Privatpersonen. Bei der Ausf\u00fchrung unserer Auftr\u00e4ge streben wir neben Pr\u00e4zision auch Schnelligkeit und die genaue Einhaltung der vereinbarten Fristen unter allen Umst\u00e4nden an.","breadcrumb":{"@id":"https:\/\/profiforditas.hu\/bemutatkozas\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/profiforditas.hu\/bemutatkozas\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/profiforditas.hu\/bemutatkozas\/#primaryimage","url":"https:\/\/profiforditas.hu\/wp-content\/uploads\/2026\/05\/logo-1.webp","contentUrl":"https:\/\/profiforditas.hu\/wp-content\/uploads\/2026\/05\/logo-1.webp","width":800,"height":177},{"@type":"BreadcrumbList","@id":"https:\/\/profiforditas.hu\/bemutatkozas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/profiforditas.hu\/"},{"@type":"ListItem","position":2,"name":"Bemutatkoz\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/profiforditas.hu\/#website","url":"https:\/\/profiforditas.hu\/","name":"\u00dcbersetzungsb\u00fcro","description":"Profi ford\u00edt\u00e1sok gyorsan \u00e9s egyszer\u0171en!","publisher":{"@id":"https:\/\/profiforditas.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/profiforditas.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/profiforditas.hu\/#organization","name":"\u00dcbersetzungsb\u00fcro","url":"https:\/\/profiforditas.hu\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/profiforditas.hu\/#\/schema\/logo\/image\/","url":"https:\/\/profiforditas.hu\/wp-content\/uploads\/2026\/05\/logo-1.webp","contentUrl":"https:\/\/profiforditas.hu\/wp-content\/uploads\/2026\/05\/logo-1.webp","width":800,"height":177,"caption":"Ford\u00edt\u00f3 iroda"},"image":{"@id":"https:\/\/profiforditas.hu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/profiforditas.hu\/de\/wp-json\/wp\/v2\/pages\/487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/profiforditas.hu\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/profiforditas.hu\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/profiforditas.hu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/profiforditas.hu\/de\/wp-json\/wp\/v2\/comments?post=487"}],"version-history":[{"count":16,"href":"https:\/\/profiforditas.hu\/de\/wp-json\/wp\/v2\/pages\/487\/revisions"}],"predecessor-version":[{"id":503,"href":"https:\/\/profiforditas.hu\/de\/wp-json\/wp\/v2\/pages\/487\/revisions\/503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/profiforditas.hu\/de\/wp-json\/wp\/v2\/media\/527"}],"wp:attachment":[{"href":"https:\/\/profiforditas.hu\/de\/wp-json\/wp\/v2\/media?parent=487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}